{"id":5982,"date":"2025-05-23T18:12:33","date_gmt":"2025-05-23T22:12:33","guid":{"rendered":"https:\/\/culturalpr.com\/notas\/?p=5982"},"modified":"2025-05-23T18:46:34","modified_gmt":"2025-05-23T22:46:34","slug":"agenda-cultural-del-23-de-mayo-al-1ro-de-junio-de-2025","status":"publish","type":"post","link":"https:\/\/culturalpr.com\/notas\/agenda-cultural-del-23-de-mayo-al-1ro-de-junio-de-2025\/","title":{"rendered":"Agenda cultural del 23 de mayo al 1ro de junio de 2025"},"content":{"rendered":"<h6>#P\u00e1salaCultural todos los d\u00edas<\/h6>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" wp-image-5984 aligncenter\" src=\"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Semana-de-la-Danza-300x86.png\" alt=\"\" width=\"719\" height=\"206\" srcset=\"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Semana-de-la-Danza-300x86.png 300w, https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Semana-de-la-Danza-370x106.png 370w, https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Semana-de-la-Danza.png 700w\" sizes=\"(max-width: 767px) 100vw, 719px\" \/><\/p>\n<p><strong>53ra Semana de la Danza Puertorrique\u00f1a<\/strong><br \/>\nEl Instituto de Cultura Puertorrique\u00f1a celebrar\u00e1 la 53ra Semana de la Danza Puertorrique\u00f1a con un concierto gratuito y la premiaci\u00f3n del Concurso de Composici\u00f3n de Danza para Guitarra Cl\u00e1sica, este domingo 25 de mayo a las 4:00 p. m. en el Teatro Francisco Arriv\u00ed en Santurce. Durante el evento, se interpretar\u00e1n las tres obras ganadoras a cargo del guitarrista Hermelindo Ruiz Mestre, junto a presentaciones especiales del maestro Luciano Qui\u00f1ones, el D\u00fao Copla y un cantante sorpresa. Los premios del concurso reconocen el talento musical con incentivos de $1,000, $500 y $300 para los tres primeros lugares. Esta iniciativa busca promover la danza puertorrique\u00f1a, apoyar a nuevos talentos y fortalecer la identidad cultural del pa\u00eds. La celebraci\u00f3n responde a la Ley N\u00fam. 20, que fomenta la creatividad y el desarrollo musical en honor a Juan Morel Campos.<br \/>\nDETALLES EN <a href=\"https:\/\/culturalpr.com\/notas\/instituto-de-cultura-puertorriquena-realizara-concierto-gratuito-para-celebrar-la-53ra-semana-de-la-danza-puertorriquena\/\">https:\/\/culturalpr.com\/notas\/instituto-de-cultura-puertorriquena-realizara-concierto-gratuito-para-celebrar-la-53ra-semana-de-la-danza-puertorriquena\/<\/a><\/p>\n<p><img decoding=\"async\" class=\" wp-image-5955 aligncenter\" src=\"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Teatro-en-15-300x86.png\" alt=\"\" width=\"719\" height=\"206\" srcset=\"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Teatro-en-15-300x86.png 300w, https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Teatro-en-15-370x106.png 370w, https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Teatro-en-15.png 700w\" sizes=\"(max-width: 767px) 100vw, 719px\" \/><\/p>\n<p><strong>Nueva temporada de Teatro en 15<\/strong><br \/>\nEste mes de mayo regresa la nueva temporada de Teatro en 15, trayendo consigo seis obras distintas que prometen sorprenderte. Cada funci\u00f3n dura solo 15 minutos, ideal para quienes buscan experiencias teatrales intensas y breves. Los elencos est\u00e1n llenos de talento local y las historias son tan variadas como memorables. No te pierdas la oportunidad de disfrutar cada funci\u00f3n por solo $5.<br \/>\nFunciones jueves a domingo<br \/>\nJueves a s\u00e1bado: 6PM-10PM<br \/>\nDomingo: 1PM-5PM<\/p>\n<p><img decoding=\"async\" class=\" wp-image-5952 aligncenter\" src=\"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Soy-Menopausica\u2026-\u00a1y-Que-300x86.png\" alt=\"\" width=\"719\" height=\"206\" srcset=\"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Soy-Menopausica\u2026-\u00a1y-Que-300x86.png 300w, https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Soy-Menopausica\u2026-\u00a1y-Que-370x106.png 370w, https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Soy-Menopausica\u2026-\u00a1y-Que.png 700w\" sizes=\"(max-width: 767px) 100vw, 719px\" \/><\/p>\n<p><strong>Soy Menop\u00e1usica\u2026 \u00a1y Qu\u00e9!<\/strong><br \/>\nStudio 58 Guayama est\u00e1 casi listo para recibir al p\u00fablico con su primer mes de apertura, y una de las grandes atracciones es el stand-up de Marian Pab\u00f3n, \u201cSoy Menop\u00e1usica\u2026 \u00a1y Qu\u00e9!\u201d. Esta comedia para adultos se presentar\u00e1 el 23 y 24 de mayo en Guayama y el 30 de mayo en Ponce, prometiendo una noche llena de risas y desahogos. Es solo el comienzo de muchas sorpresas que el estudio tiene preparadas para este mes. No pierdas la oportunidad de ser parte de esta divertida experiencia.<br \/>\n<a href=\"https:\/\/pietix.com\/soy-menopausica-y-que?fbclid=IwY2xjawKXZQ5leHRuA2FlbQIxMABicmlkETFuZ29lekdoazd4c3h4anNWAR41ovEkChKqnOoU3cWtKIWIJqrchgfAcS_VrtrzdECbtRGFsBBD_LOrM-vFoQ_aem_vC07Z0O9lx633lMU5qTtqg\">BOLETOS \ud83c\udf9f\ufe0f<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-5985 aligncenter\" src=\"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Volvere-1-300x86.png\" alt=\"\" width=\"722\" height=\"207\" srcset=\"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Volvere-1-300x86.png 300w, https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Volvere-1-370x106.png 370w, https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Volvere-1.png 700w\" sizes=\"(max-width: 767px) 100vw, 722px\" \/><\/p>\n<p><strong>Volver\u00e9<\/strong><br \/>\n<strong>24 de mayo en A\u00f1asco<\/strong><\/p>\n<p>El Programa de Artes Esc\u00e9nicas del Instituto de Cultura Puertorrique\u00f1a (ICP) presenta Volver\u00e9, una innovadora propuesta esc\u00e9nica de la teatrera, performera, mascarera, titiritera y artista visual Deborah Hunt, como parte de su Residencia Art\u00edstica 2025. Esta obra de surrealismo m\u00e1gico sigue a una viajera misteriosa que teje sus relatos acompa\u00f1ada por tres animales fant\u00e1sticos -un zorro, una rata y un cuervo- provenientes de un bestiario del futuro. A trav\u00e9s de objetos animados, teatro de papel, sombras chinescas y \u201ctoy theatre\u201d con personajes bidimensionales, Volver\u00e9 celebra lo extra\u00f1o y maravilloso, fusionando t\u00e9cnicas ancestrales con una visi\u00f3n contempor\u00e1nea que impulsa la imaginaci\u00f3n y rescata el arte del objeto animado.<\/p>\n<p>Esta pieza, que forma parte del 62\u00ba Festival de Teatro Puertorrique\u00f1o, invita al p\u00fablico a sumergirse en un mundo visual y sensorial \u00fanico, donde la narrativa se construye sin palabras, solo con im\u00e1genes, movimientos y objetos. Deborah Hunt, con m\u00e1s de 35 a\u00f1os de trayectoria en Puerto Rico, contin\u00faa explorando y expandiendo los l\u00edmites del teatro experimental, ofreciendo una experiencia art\u00edstica profunda y transformadora.<\/p>\n<p>Volver\u00e9 se presentar\u00e1 en el Teatro Victoria Espinosa en Santurce, el 9 y 10 de mayo a las 8:00 p.m. y el 11 de mayo a las 5:00 p.m. Los boletos se pueden adquirir en Ticketera.com. Mientras que las otras funciones ser\u00e1n las siguientes:<br \/>\nMuseo de Arte de Ponce<br \/>\n15 de mayo a las 6:30 PM | Donativo sugerido $5.00<br \/>\nCiudad Museo PR, A\u00f1asco<br \/>\n24 de mayo a las 6:00 PM | Donativo sugerido $5.00<br \/>\nTaller Libert\u00e1, Mayag\u00fcez<br \/>\n7 de junio a las 8:00 PM | Donativo sugerido $10.00<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-5986 aligncenter\" src=\"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Ana-del-rOCIO-1-300x86.png\" alt=\"\" width=\"719\" height=\"206\" srcset=\"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Ana-del-rOCIO-1-300x86.png 300w, https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Ana-del-rOCIO-1-370x106.png 370w, https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Ana-del-rOCIO-1.png 700w\" sizes=\"(max-width: 767px) 100vw, 719px\" \/><\/p>\n<p><strong>Ana del Roc\u00edo: El Bolero en Puerto Rico \u2013 Historia &amp; Patrimonio<\/strong><\/p>\n<p>Ana del Roc\u00edo, en colaboraci\u00f3n con el Instituto de Cultura Puertorrique\u00f1a (ICP), presenta el proyecto educativo y musical El Bolero en Puerto Rico \u2013 Historia &amp; Patrimonio, que combina un taller interactivo con un espect\u00e1culo para celebrar el legado del bolero en la isla. Esta iniciativa recorre la historia, desarrollo e impacto del g\u00e9nero, destacando a grandes compositores e int\u00e9rpretes puertorrique\u00f1os como Tite Curet Alonso, Rafael Hern\u00e1ndez y Sylvia Rexach, entre otros. Ana del Roc\u00edo expresa su pasi\u00f3n por el bolero y la historia, y busca fomentar el amor por este g\u00e9nero declarado Patrimonio Cultural Inmaterial de la Humanidad por la UNESCO en 2024. La gira incluir\u00e1 presentaciones en diversos centros culturales de Puerto Rico, con entrada libre para el p\u00fablico general. Adem\u00e1s, el proyecto incluye un mini documental con entrevistas a expertos, enriqueciendo a\u00fan m\u00e1s esta experiencia cultural.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-5953 aligncenter\" src=\"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Voces-de-la-luna-300x86.png\" alt=\"\" width=\"719\" height=\"206\" srcset=\"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Voces-de-la-luna-300x86.png 300w, https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Voces-de-la-luna-370x106.png 370w, https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Voces-de-la-luna.png 700w\" sizes=\"(max-width: 767px) 100vw, 719px\" \/><\/p>\n<p><strong>Coro de Ni\u00f1os de San Juan: Voces de la Luna<\/strong><br \/>\nEl Coro de Ni\u00f1os de San Juan presenta \u201cVoces de la Luna\u201d, un concierto que combina m\u00fasica y teatro para explorar un mundo de sue\u00f1os, estrellas y esperanza. La compa\u00f1\u00eda Y no hab\u00eda luz crea una historia m\u00e1gica que acompa\u00f1a un repertorio po\u00e9tico, invitando al p\u00fablico a un viaje emocional y lleno de fantas\u00eda. Las melod\u00edas y la actuaci\u00f3n buscan tocar el coraz\u00f3n y despertar la imaginaci\u00f3n de todos los asistentes. Las funciones ser\u00e1n el 24 y 25 de mayo en la Sala Ren\u00e9 Marqu\u00e9s del Centro de Bellas Artes Luis A. Ferr\u00e9.<br \/>\n<a href=\"https:\/\/tcpr.com\/he-IL\/categories\/cba%20-%20san%20juan?fbclid=IwY2xjawKXYHFleHRuA2FlbQIxMABicmlkETFuZ29lekdoazd4c3h4anNWAR7WdHg4Krg9Wx5OSnr-yFBfGV9fLZLG4elsnp4JcuL1H3FevdOJpuUqAbr-UQ_aem_eOFX6S9yvm894yvXfHWi8Q\">BOLETOS\ud83c\udf9f\ufe0f<\/a><\/p>\n<p>S\u00e1bado, 24-mayo-2025, 7:00pm<br \/>\nDomingo, 25-mayo-2025, 4:00pm<br \/>\nSala Ren\u00e9 Marqu\u00e9s<br \/>\nCentro de Bellas Artes Luis A. Ferr\u00e9<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-5902 aligncenter\" src=\"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Como-Coco-300x86.png\" alt=\"\" width=\"719\" height=\"206\" srcset=\"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Como-Coco-300x86.png 300w, https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Como-Coco-370x106.png 370w, https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Como-Coco.png 700w\" sizes=\"(max-width: 767px) 100vw, 719px\" \/><\/p>\n<p><strong>Como Coco<\/strong><br \/>\nen el Teatro Yag\u00fcez<br \/>\nElena (\u00c1ngela Meyer) y Leandro (Ren\u00e9 Monclova) son dos adultos mayores hipocondr\u00edacos que, mientras esperan en la sala del Doctor Bolt (Raymond Gerena), descubren un nuevo \u201cachaque\u201d: la lujuria y la pasi\u00f3n. A escondidas de sus hijos Luisa (Sara Jarque) y Julio (Danilo Beuchamp), estos dos se enamoran con la intensidad de adolescentes, desatando una comedia llena de humor, amor y rebeld\u00eda.<\/p>\n<p>\u201cComo Coco\u201d explora si el amor podr\u00e1 vencer a los achaques y si las citas m\u00e9dicas se transformar\u00e1n en citas rom\u00e1nticas. Bajo un tono divertido y fresco, esta obra demuestra que el amor no tiene edad, aunque s\u00ed receta.<\/p>\n<p><a href=\"https:\/\/www.ticketera.com\/events\/detail\/como-coco-sxc9wt\">BOLETOS\ud83c\udf9f\ufe0f<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-5987 aligncenter\" src=\"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/AINADAMAR-300x86.png\" alt=\"\" width=\"719\" height=\"206\" srcset=\"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/AINADAMAR-300x86.png 300w, https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/AINADAMAR-370x106.png 370w, https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/AINADAMAR.png 700w\" sizes=\"(max-width: 767px) 100vw, 719px\" \/><\/p>\n<p><strong>AINADAMAR: La Tragedia de Lorca en \u00d3pera<\/strong><br \/>\nLa \u00f3pera Ainadamar, obra del compositor argentino Osvaldo Golijov y ganadora del premio Grammy, se presentar\u00e1 el 24 de mayo en la Sala de Festivales con una producci\u00f3n que promete cautivar al p\u00fablico. Esta pieza relata la vida y legado del poeta Federico Garc\u00eda Lorca a trav\u00e9s de los recuerdos de Margarita Xirgu, su amiga y musa, quien revive su profunda conexi\u00f3n y el tr\u00e1gico destino de Lorca durante la Guerra Civil Espa\u00f1ola. El libreto, escrito por David Henry Hwang y traducido al espa\u00f1ol por el propio Golijov, se fusiona con una m\u00fasica vibrante que mezcla el lirismo oper\u00e1tico, la intensidad del flamenco y los ritmos de la rumba, haciendo del baile una poderosa herramienta narrativa. La Orquesta Sinf\u00f3nica de Puerto Rico, bajo la direcci\u00f3n de Maximiano Vald\u00e9s, ser\u00e1 la encargada de acompa\u00f1ar a un elenco internacional encabezado por Jessica Rivera, Meechot Marrero y Evelyn Ram\u00edrez. Esta \u00f3pera en un acto y tres im\u00e1genes ofrece una experiencia art\u00edstica \u00fanica, donde la historia, la m\u00fasica y la danza se entrelazan para rendir homenaje a uno de los grandes poetas del siglo XX.<\/p>\n<p>\u00d3pera en un acto y tres im\u00e1genes<\/p>\n<p>Libreto de David Henry Hwang traducido al espa\u00f1ol por Osvaldo Golijov<br \/>\nOrquesta Sinf\u00f3nica de Puerto Rico<\/p>\n<p>Maximiano Vald\u00e9s, director titular<br \/>\nMarcelo Lombardero, director esc\u00e9nico<br \/>\nElenco:<\/p>\n<p>Margarita Xirgu Jessica Rivera, soprano<\/p>\n<p>Nuria Meechot Marrero, soprano<\/p>\n<p>Federico Garc\u00eda Lorca Evelyn Ram\u00edrez, mezzo soprano<\/p>\n<p>Ram\u00f3n Ruiz Alonso Alfredo Tejada, cantaor<\/p>\n<p>Voz de la fuente Camila Otero, soprano<\/p>\n<p>Voz de la fuente Aurora Navarro, mezzosoprano<\/p>\n<p>Maestro Carlos Ortiz, tenor<\/p>\n<p>Torero Jeh\u00fa Otero, tenor<\/p>\n<p>Jos\u00e9 Tripaldi Ricardo Sep\u00falveda, bar\u00edtono<\/p>\n<p><a href=\"https:\/\/www.ticketera.com\/events\/detail\/ainadamar-la-tragedia-de-lorca-en-opera\">BOLETOS \ud83c\udf9f\ufe0f<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-5954 aligncenter\" src=\"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Duo-Figueroa-50-anos-de-virtuosismo-300x86.png\" alt=\"\" width=\"719\" height=\"206\" srcset=\"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Duo-Figueroa-50-anos-de-virtuosismo-300x86.png 300w, https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Duo-Figueroa-50-anos-de-virtuosismo-370x106.png 370w, https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Duo-Figueroa-50-anos-de-virtuosismo.png 700w\" sizes=\"(max-width: 767px) 100vw, 719px\" \/><\/p>\n<p><strong>D\u00fao Figueroa: 50 a\u00f1os de virtuosismo<\/strong><br \/>\nEl Festival Casals celebra el 50\u00ba aniversario del debut de los hermanos Ivonne y Guillermo Figueroa con un recital especial en la Sala Sinf\u00f3nica Pablo Casals, el domingo 25 de mayo a las 4PM. Este evento presenta un repertorio que mezcla el romanticismo, la m\u00fasica del siglo XX y el folclore hispanoamericano, mostrando la versatilidad y virtuosismo de ambos m\u00fasicos. Como miembros de la reconocida Familia Figueroa, su legado musical ha dejado una marca imborrable en la escena internacional. Es una noche para disfrutar, celebrar la tradici\u00f3n y el arte de dos grandes artistas.<\/p>\n<p>Programa:<br \/>\nSonatina Op. 137, n\u00fam. 1 en re mayor<br \/>\nFranz Schubert<br \/>\nSonata en la mayor<br \/>\nC\u00e9sar Franck<br \/>\nSonata No. 1 Op. 80 en fa menor<br \/>\nSergei Prokofiev<br \/>\nCandorosa &#8211; danza puertorrique\u00f1a<br \/>\nJes\u00fas Figueroa<br \/>\nDanza espa\u00f1ola (La vida breve)<br \/>\nManuel de Falla<br \/>\n*El programa est\u00e1 sujeto a cambios.<\/p>\n<p><a href=\"https:\/\/shop.ticketera.com\/checkout\/festival-\">BOLETOS \ud83c\udf9f\ufe0f<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-5868 aligncenter\" src=\"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/PhotoFinish-300x86.png\" alt=\"\" width=\"722\" height=\"207\" srcset=\"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/PhotoFinish-300x86.png 300w, https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/PhotoFinish-370x106.png 370w, https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/PhotoFinish.png 700w\" sizes=\"(max-width: 767px) 100vw, 722px\" \/><\/p>\n<p><strong>Contin\u00faa hasta el 29 de mayo<\/strong><br \/>\n<strong>Photo Finish<\/strong><br \/>\nUna mirada profunda al arte y la comunicaci\u00f3n a trav\u00e9s de la fotograf\u00eda.<br \/>\nLa Asociaci\u00f3n de Estudiantes de Fotograf\u00eda de la Universidad presenta una exhibici\u00f3n que re\u00fane talentos diversos para celebrar la fotograf\u00eda como un lenguaje visual que narra historias, preserva la memoria y conecta culturas.<br \/>\nDETALLES EN <a href=\"https:\/\/culturalpr.com\/notas\/photo-finish-una-mirada-profunda-al-arte-y-la-comunicacion-a-traves-de-la-fotografia\/\">https:\/\/culturalpr.com\/notas\/photo-finish-una-mirada-profunda-al-arte-y-la-comunicacion-a-traves-de-la-fotografia\/<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-5988 aligncenter\" src=\"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Recital-de-piano-con-INGRID-FLITER-300x86.png\" alt=\"\" width=\"719\" height=\"206\" srcset=\"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Recital-de-piano-con-INGRID-FLITER-300x86.png 300w, https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Recital-de-piano-con-INGRID-FLITER-370x106.png 370w, https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Recital-de-piano-con-INGRID-FLITER.png 700w\" sizes=\"(max-width: 767px) 100vw, 719px\" \/><\/p>\n<p><strong>Recital de piano con INGRID FLITER: Un homenaje al romanticismo<\/strong><br \/>\nParte del Festival Casals<br \/>\nEl jueves 29 de mayo a las 7:00 p.m., la reconocida pianista argentina Ingrid Fliter ofrecer\u00e1 un recital en el Conservatorio de M\u00fasica de Puerto Rico, dedicado a un homenaje al romanticismo. En este concierto, Fliter interpretar\u00e1 obras emblem\u00e1ticas de Fr\u00e9d\u00e9ric Chopin y Robert Schumann, incluyendo la Sonata n\u00fam. 3, Op. 58 de Chopin y los exigentes Estudios Sinf\u00f3nicos, Op. 13 de Schumann. El programa tambi\u00e9n incluye las emotivas &#8220;Escenas de la infancia&#8221; (Kinderszenen, Op. 15) de Schumann, que reflejan la riqueza expresiva del periodo rom\u00e1ntico. Este recital promete una experiencia musical profunda y virtuosa, ideal para amantes del piano y la m\u00fasica cl\u00e1sica. Los boletos est\u00e1n disponibles, con un precio especial para estudiantes de $10 en la boleter\u00eda el d\u00eda del concierto.<\/p>\n<p>Programa:<\/p>\n<p>Kinderszenen, Op. 15 (Escenas de la infancia)<\/p>\n<p>Robert Schumann<br \/>\nSonata n\u00fam. 3, Op. 58<\/p>\n<p>Fr\u00e9d\u00e9ric Chopin (vea su interpretaci\u00f3n de esta sonata aqu\u00ed <a href=\"https:\/\/www.youtube.com\/watch?v=JWpM9rmMIzc\">\u00a0https:\/\/www.youtube.com\/watch?v=JWpM9rmMIzc<\/a>)<br \/>\nEtudes symphoniques, Op. 13 (Estudios sinf\u00f3nicos)<\/p>\n<p>Robert Schumann<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-5989 aligncenter\" src=\"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Catalyst-Quartet-en-Concierto-300x86.png\" alt=\"\" width=\"719\" height=\"206\" srcset=\"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Catalyst-Quartet-en-Concierto-300x86.png 300w, https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Catalyst-Quartet-en-Concierto-370x106.png 370w, https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Catalyst-Quartet-en-Concierto.png 700w\" sizes=\"(max-width: 767px) 100vw, 719px\" \/><\/p>\n<p><strong>Catalyst Quartet en Concierto<\/strong><br \/>\nEl aclamado Catalyst Quartet regresa a Puerto Rico para presentarse el viernes 30 de mayo en el Conservatorio de M\u00fasica, reafirmando su compromiso con la diversidad, la educaci\u00f3n y la excelencia musical. El ensamble, integrado por Karla Donehew P\u00e9rez, Abi Fayette, Paul Laraia y Karlos Rodr\u00edguez, es reconocido internacionalmente por su unidad, precisi\u00f3n y pasi\u00f3n tanto por la m\u00fasica cl\u00e1sica como contempor\u00e1nea. En esta ocasi\u00f3n, interpretar\u00e1n piezas de Piazzolla, Gershwin, Ravel y D\u2019Rivera, resaltando su enfoque en la innovaci\u00f3n y la representaci\u00f3n de compositores hist\u00f3ricamente subrepresentados. Adem\u00e1s, ofrecer\u00e1n una clase magistral gratuita en Dorado como parte de su misi\u00f3n educativa. La visita del cuarteto, elogiado por su t\u00e9cnica y emotividad, promete enriquecer la escena musical puertorrique\u00f1a y brindar una experiencia inolvidable al p\u00fablico.<br \/>\nDETALLES EN <a href=\"https:\/\/culturalpr.com\/notas\/catalyst-quartet-en-concierto\/\">https:\/\/culturalpr.com\/notas\/catalyst-quartet-en-concierto\/<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-5903 aligncenter\" src=\"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Vakil-300x86.png\" alt=\"\" width=\"719\" height=\"206\" srcset=\"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Vakil-300x86.png 300w, https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Vakil-370x106.png 370w, https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Vakil.png 700w\" sizes=\"(max-width: 767px) 100vw, 719px\" \/><\/p>\n<p><strong>Contin\u00faa hasta el 31 de mayo<\/strong><br \/>\n<strong>Exposici\u00f3n individual de 3t Vakil<\/strong><\/p>\n<p>El Museo de Arte y Cultura de Patillas presenta Spandrel Spaces de 3t Vakil, una exposici\u00f3n que explora la conexi\u00f3n entre la naturaleza y el arte.<br \/>\nInauguraci\u00f3n: s\u00e1bado 17 de mayo de 2025, con la artista presente.<br \/>\nDETALLES en <a href=\"https:\/\/culturalpr.com\/notas\/exposicion-individual-de-3t-vakil-en-el-museo-de-arte-y-cultura-de-patillas\/\">https:\/\/culturalpr.com\/notas\/exposicion-individual-de-3t-vakil-en-el-museo-de-arte-y-cultura-de-patillas\/<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-5747 aligncenter\" src=\"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/04\/Prometea-Cansada-300x86.png\" alt=\"\" width=\"715\" height=\"205\" srcset=\"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/04\/Prometea-Cansada-300x86.png 300w, https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/04\/Prometea-Cansada-370x106.png 370w, https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/04\/Prometea-Cansada.png 700w\" sizes=\"(max-width: 767px) 100vw, 715px\" \/><\/p>\n<p><strong>Contin\u00faa hastael 1ro de junio <\/strong><br \/>\n<strong>El Mundo Seg\u00fan Mafalda<\/strong><br \/>\nEsta muestra, que se llevar\u00e1 a cabo del 18 de abril al 1 de junio de 2025 en el Instituto de Cultura Puertorrique\u00f1a, ofrece una experiencia educativa y divertida para todas las edades. Los visitantes podr\u00e1n disfrutar de instalaciones interactivas, arte original y los temas m\u00e1s emblem\u00e1ticos de la historieta a trav\u00e9s de recorridos guiados que duran aproximadamente una hora y cuarenta y cinco minutos.<br \/>\nDETALLES y boletos en <a href=\"https:\/\/culturalpr.com\/notas\/el-mundo-segun-mafalda\/\">https:\/\/culturalpr.com\/notas\/el-mundo-segun-mafalda\/<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-5997 aligncenter\" src=\"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/ZOETROPE-300x86.png\" alt=\"\" width=\"715\" height=\"205\" srcset=\"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/ZOETROPE-300x86.png 300w, https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/ZOETROPE-370x106.png 370w, https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/ZOETROPE.png 700w\" sizes=\"(max-width: 767px) 100vw, 715px\" \/><\/p>\n<p><strong>Zoetrope<\/strong><\/p>\n<p><strong>parte del 62do Festival de Teatro Puertorrique\u00f1o<\/strong><\/p>\n<p>Zoetrope es una experiencia teatral innovadora e h\u00edbrida que entrelaza el cine y el teatro para explorar la di\u00e1spora puertorrique\u00f1a. Inspirada en cartas reales entre Lares y Manhattan, la obra sigue la historia de Severino, un cartero militar que emigra a Nueva York en los a\u00f1os \u201850 en busca de una vida mejor. A trav\u00e9s de una narrativa fragmentada que mezcla flashbacks, cortes paralelos y video en vivo, Zoetrope da vida a generaciones de una familia trabajadora marcada por el amor, la pol\u00edtica y la p\u00e9rdida.<\/p>\n<p>Descrita por The New Yorker como &#8220;sumamente divertida y rom\u00e1ntica,\u201d Zoetrope ofrece una visi\u00f3n caleidosc\u00f3pica del desarraigo y la memoria. Presentada en ingl\u00e9s y espa\u00f1ol, con supert\u00edtulos en ambos idiomas, Zoetrope es un viaje sensorial que desdibuja los l\u00edmites entre realidad y representaci\u00f3n, invitando al p\u00fablico a mirar el pasado con nuevos ojos.<\/p>\n<p>Esta obra se presenta como parte del 62 Festival Puertorrique\u00f1o del Instituto de Cultura Puertorrique\u00f1a. Las funciones del 29 al 31 de mayo son a las 7:00 p.m. y el 1 de junio a las 4:00 p.m. Los boletos esta disponible en PRTicket.com.<\/p>\n<p><a href=\"https:\/\/boletos.prticket.com\/events\/en\/zoetrope\">Boletos \ud83c\udf9f\ufe0f<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-5990 aligncenter\" src=\"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Fest-Teatro-PR-300x86.png\" alt=\"\" width=\"715\" height=\"205\" srcset=\"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Fest-Teatro-PR-300x86.png 300w, https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Fest-Teatro-PR-370x106.png 370w, https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Fest-Teatro-PR.png 700w\" sizes=\"(max-width: 767px) 100vw, 715px\" \/><\/p>\n<p><strong>Contin\u00faa el<\/strong><\/p>\n<p><strong>62do Festival de Teatro Puertorrique\u00f1o<\/strong><\/p>\n<p><a href=\"https:\/\/culturalpr.com\/notas\/programa-del-62do-festival-de-teatro-puertorriqueno\/\">vea el PROGRAMA aqu\u00ed<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>#P\u00e1salaCultural todos los d\u00edas 53ra Semana de la Danza Puertorrique\u00f1a El Instituto de Cultura Puertorrique\u00f1a celebrar\u00e1 la 53ra Semana de la Danza Puertorrique\u00f1a con un concierto gratuito y la premiaci\u00f3n del Concurso de Composici\u00f3n de Danza para Guitarra Cl\u00e1sica, este domingo 25&hellip;<\/p>\n","protected":false},"author":990002,"featured_media":5983,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","footnotes":""},"categories":[171],"tags":[],"class_list":["post-5982","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Agenda cultural del 23 de mayo al 1ro de junio de 2025 - CulturalPR - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/culturalpr.com\/notas\/agenda-cultural-del-23-de-mayo-al-1ro-de-junio-de-2025\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Agenda cultural del 23 de mayo al 1ro de junio de 2025 - CulturalPR - Noticias\" \/>\n<meta property=\"og:description\" content=\"#P\u00e1salaCultural todos los d\u00edas 53ra Semana de la Danza Puertorrique\u00f1a El Instituto de Cultura Puertorrique\u00f1a celebrar\u00e1 la 53ra Semana de la Danza Puertorrique\u00f1a con un concierto gratuito y la premiaci\u00f3n del Concurso de Composici\u00f3n de Danza para Guitarra Cl\u00e1sica, este domingo 25&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/culturalpr.com\/notas\/agenda-cultural-del-23-de-mayo-al-1ro-de-junio-de-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"CulturalPR - Noticias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/culturalpr\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-23T22:12:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-23T22:46:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Agenda-CulturaolPR-22-al-31-de-mayo-de-2025.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Rosalba Medina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@PasalaCultural\" \/>\n<meta name=\"twitter:site\" content=\"@PasalaCultural\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rosalba Medina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/agenda-cultural-del-23-de-mayo-al-1ro-de-junio-de-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/agenda-cultural-del-23-de-mayo-al-1ro-de-junio-de-2025\\\/\"},\"author\":{\"name\":\"Rosalba Medina\",\"@id\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/#\\\/schema\\\/person\\\/fcbcffce6aa09e518334849b38486e54\"},\"headline\":\"Agenda cultural del 23 de mayo al 1ro de junio de 2025\",\"datePublished\":\"2025-05-23T22:12:33+00:00\",\"dateModified\":\"2025-05-23T22:46:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/agenda-cultural-del-23-de-mayo-al-1ro-de-junio-de-2025\\\/\"},\"wordCount\":2258,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/agenda-cultural-del-23-de-mayo-al-1ro-de-junio-de-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Agenda-CulturaolPR-22-al-31-de-mayo-de-2025.png\",\"articleSection\":[\"NOTICIAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/culturalpr.com\\\/notas\\\/agenda-cultural-del-23-de-mayo-al-1ro-de-junio-de-2025\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/agenda-cultural-del-23-de-mayo-al-1ro-de-junio-de-2025\\\/\",\"url\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/agenda-cultural-del-23-de-mayo-al-1ro-de-junio-de-2025\\\/\",\"name\":\"Agenda cultural del 23 de mayo al 1ro de junio de 2025 - CulturalPR - Noticias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/agenda-cultural-del-23-de-mayo-al-1ro-de-junio-de-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/agenda-cultural-del-23-de-mayo-al-1ro-de-junio-de-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Agenda-CulturaolPR-22-al-31-de-mayo-de-2025.png\",\"datePublished\":\"2025-05-23T22:12:33+00:00\",\"dateModified\":\"2025-05-23T22:46:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/agenda-cultural-del-23-de-mayo-al-1ro-de-junio-de-2025\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/culturalpr.com\\\/notas\\\/agenda-cultural-del-23-de-mayo-al-1ro-de-junio-de-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/agenda-cultural-del-23-de-mayo-al-1ro-de-junio-de-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Agenda-CulturaolPR-22-al-31-de-mayo-de-2025.png\",\"contentUrl\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Agenda-CulturaolPR-22-al-31-de-mayo-de-2025.png\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/agenda-cultural-del-23-de-mayo-al-1ro-de-junio-de-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Agenda cultural del 23 de mayo al 1ro de junio de 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/#website\",\"url\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/\",\"name\":\"CulturalPR - Noticias\",\"description\":\"Puerto Rico\",\"publisher\":{\"@id\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/#organization\",\"name\":\"CulturalPR - Noticias\",\"url\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Untitled-design.png\",\"contentUrl\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Untitled-design.png\",\"width\":940,\"height\":788,\"caption\":\"CulturalPR - Noticias\"},\"image\":{\"@id\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/culturalpr\",\"https:\\\/\\\/x.com\\\/PasalaCultural\",\"https:\\\/\\\/www.instagram.com\\\/culturalpr\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/#\\\/schema\\\/person\\\/fcbcffce6aa09e518334849b38486e54\",\"name\":\"Rosalba Medina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2803a8602f74f9b5a53ce7e64cbade1dd09ac45aab49c75e6b85bdd91dc93b21?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2803a8602f74f9b5a53ce7e64cbade1dd09ac45aab49c75e6b85bdd91dc93b21?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2803a8602f74f9b5a53ce7e64cbade1dd09ac45aab49c75e6b85bdd91dc93b21?s=96&d=mm&r=g\",\"caption\":\"Rosalba Medina\"},\"url\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/author\\\/rosalba\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Agenda cultural del 23 de mayo al 1ro de junio de 2025 - CulturalPR - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/culturalpr.com\/notas\/agenda-cultural-del-23-de-mayo-al-1ro-de-junio-de-2025\/","og_locale":"es_ES","og_type":"article","og_title":"Agenda cultural del 23 de mayo al 1ro de junio de 2025 - CulturalPR - Noticias","og_description":"#P\u00e1salaCultural todos los d\u00edas 53ra Semana de la Danza Puertorrique\u00f1a El Instituto de Cultura Puertorrique\u00f1a celebrar\u00e1 la 53ra Semana de la Danza Puertorrique\u00f1a con un concierto gratuito y la premiaci\u00f3n del Concurso de Composici\u00f3n de Danza para Guitarra Cl\u00e1sica, este domingo 25&hellip;","og_url":"https:\/\/culturalpr.com\/notas\/agenda-cultural-del-23-de-mayo-al-1ro-de-junio-de-2025\/","og_site_name":"CulturalPR - Noticias","article_publisher":"https:\/\/www.facebook.com\/culturalpr","article_published_time":"2025-05-23T22:12:33+00:00","article_modified_time":"2025-05-23T22:46:34+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Agenda-CulturaolPR-22-al-31-de-mayo-de-2025.png","type":"image\/png"}],"author":"Rosalba Medina","twitter_card":"summary_large_image","twitter_creator":"@PasalaCultural","twitter_site":"@PasalaCultural","twitter_misc":{"Escrito por":"Rosalba Medina","Tiempo de lectura":"13 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/culturalpr.com\/notas\/agenda-cultural-del-23-de-mayo-al-1ro-de-junio-de-2025\/#article","isPartOf":{"@id":"https:\/\/culturalpr.com\/notas\/agenda-cultural-del-23-de-mayo-al-1ro-de-junio-de-2025\/"},"author":{"name":"Rosalba Medina","@id":"https:\/\/culturalpr.com\/notas\/#\/schema\/person\/fcbcffce6aa09e518334849b38486e54"},"headline":"Agenda cultural del 23 de mayo al 1ro de junio de 2025","datePublished":"2025-05-23T22:12:33+00:00","dateModified":"2025-05-23T22:46:34+00:00","mainEntityOfPage":{"@id":"https:\/\/culturalpr.com\/notas\/agenda-cultural-del-23-de-mayo-al-1ro-de-junio-de-2025\/"},"wordCount":2258,"commentCount":0,"publisher":{"@id":"https:\/\/culturalpr.com\/notas\/#organization"},"image":{"@id":"https:\/\/culturalpr.com\/notas\/agenda-cultural-del-23-de-mayo-al-1ro-de-junio-de-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Agenda-CulturaolPR-22-al-31-de-mayo-de-2025.png","articleSection":["NOTICIAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/culturalpr.com\/notas\/agenda-cultural-del-23-de-mayo-al-1ro-de-junio-de-2025\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/culturalpr.com\/notas\/agenda-cultural-del-23-de-mayo-al-1ro-de-junio-de-2025\/","url":"https:\/\/culturalpr.com\/notas\/agenda-cultural-del-23-de-mayo-al-1ro-de-junio-de-2025\/","name":"Agenda cultural del 23 de mayo al 1ro de junio de 2025 - CulturalPR - Noticias","isPartOf":{"@id":"https:\/\/culturalpr.com\/notas\/#website"},"primaryImageOfPage":{"@id":"https:\/\/culturalpr.com\/notas\/agenda-cultural-del-23-de-mayo-al-1ro-de-junio-de-2025\/#primaryimage"},"image":{"@id":"https:\/\/culturalpr.com\/notas\/agenda-cultural-del-23-de-mayo-al-1ro-de-junio-de-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Agenda-CulturaolPR-22-al-31-de-mayo-de-2025.png","datePublished":"2025-05-23T22:12:33+00:00","dateModified":"2025-05-23T22:46:34+00:00","breadcrumb":{"@id":"https:\/\/culturalpr.com\/notas\/agenda-cultural-del-23-de-mayo-al-1ro-de-junio-de-2025\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/culturalpr.com\/notas\/agenda-cultural-del-23-de-mayo-al-1ro-de-junio-de-2025\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/culturalpr.com\/notas\/agenda-cultural-del-23-de-mayo-al-1ro-de-junio-de-2025\/#primaryimage","url":"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Agenda-CulturaolPR-22-al-31-de-mayo-de-2025.png","contentUrl":"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/05\/Agenda-CulturaolPR-22-al-31-de-mayo-de-2025.png","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/culturalpr.com\/notas\/agenda-cultural-del-23-de-mayo-al-1ro-de-junio-de-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/culturalpr.com\/notas\/"},{"@type":"ListItem","position":2,"name":"Agenda cultural del 23 de mayo al 1ro de junio de 2025"}]},{"@type":"WebSite","@id":"https:\/\/culturalpr.com\/notas\/#website","url":"https:\/\/culturalpr.com\/notas\/","name":"CulturalPR - Noticias","description":"Puerto Rico","publisher":{"@id":"https:\/\/culturalpr.com\/notas\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/culturalpr.com\/notas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/culturalpr.com\/notas\/#organization","name":"CulturalPR - Noticias","url":"https:\/\/culturalpr.com\/notas\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/culturalpr.com\/notas\/#\/schema\/logo\/image\/","url":"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2024\/03\/Untitled-design.png","contentUrl":"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2024\/03\/Untitled-design.png","width":940,"height":788,"caption":"CulturalPR - Noticias"},"image":{"@id":"https:\/\/culturalpr.com\/notas\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/culturalpr","https:\/\/x.com\/PasalaCultural","https:\/\/www.instagram.com\/culturalpr\/"]},{"@type":"Person","@id":"https:\/\/culturalpr.com\/notas\/#\/schema\/person\/fcbcffce6aa09e518334849b38486e54","name":"Rosalba Medina","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2803a8602f74f9b5a53ce7e64cbade1dd09ac45aab49c75e6b85bdd91dc93b21?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2803a8602f74f9b5a53ce7e64cbade1dd09ac45aab49c75e6b85bdd91dc93b21?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2803a8602f74f9b5a53ce7e64cbade1dd09ac45aab49c75e6b85bdd91dc93b21?s=96&d=mm&r=g","caption":"Rosalba Medina"},"url":"https:\/\/culturalpr.com\/notas\/author\/rosalba\/"}]}},"views":724,"_links":{"self":[{"href":"https:\/\/culturalpr.com\/notas\/wp-json\/wp\/v2\/posts\/5982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/culturalpr.com\/notas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/culturalpr.com\/notas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/culturalpr.com\/notas\/wp-json\/wp\/v2\/users\/990002"}],"replies":[{"embeddable":true,"href":"https:\/\/culturalpr.com\/notas\/wp-json\/wp\/v2\/comments?post=5982"}],"version-history":[{"count":4,"href":"https:\/\/culturalpr.com\/notas\/wp-json\/wp\/v2\/posts\/5982\/revisions"}],"predecessor-version":[{"id":5998,"href":"https:\/\/culturalpr.com\/notas\/wp-json\/wp\/v2\/posts\/5982\/revisions\/5998"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/culturalpr.com\/notas\/wp-json\/wp\/v2\/media\/5983"}],"wp:attachment":[{"href":"https:\/\/culturalpr.com\/notas\/wp-json\/wp\/v2\/media?parent=5982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/culturalpr.com\/notas\/wp-json\/wp\/v2\/categories?post=5982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/culturalpr.com\/notas\/wp-json\/wp\/v2\/tags?post=5982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}