{"id":6223,"date":"2025-08-07T14:02:08","date_gmt":"2025-08-07T18:02:08","guid":{"rendered":"https:\/\/culturalpr.com\/notas\/?p=6223"},"modified":"2025-08-07T14:02:08","modified_gmt":"2025-08-07T18:02:08","slug":"el-nuevo-largometraje-de-maite-rivera-carbonell-destaca-entre-mas-de-700-propuestas","status":"publish","type":"post","link":"https:\/\/culturalpr.com\/notas\/el-nuevo-largometraje-de-maite-rivera-carbonell-destaca-entre-mas-de-700-propuestas\/","title":{"rendered":"El nuevo largometraje de Maite Rivera Carbonell destaca entre m\u00e1s de 700 propuestas"},"content":{"rendered":"<h5>\u00a0Es seleccionado para prestigiosa residencia en Espa\u00f1a.<\/h5>\n<p>La cineasta puertorrique\u00f1a Maite Rivera Carbonell ha sido seleccionada para participar en la vig\u00e9sima tercera edici\u00f3n del Curso de Desarrollo de Proyectos Audiovisuales Iberoamericanos (CDPAI), una reconocida residencia internacional que se celebrar\u00e1 en Madrid, Espa\u00f1a, del 29 de septiembre al 7 de noviembre de 2025.<\/p>\n<p>Su proyecto de largometraje ficci\u00f3n <em>Para\u00edso Infernal<\/em> fue escogido <strong>entre m\u00e1s de 700 propuestas de 20<\/strong> <strong>pa\u00edses<\/strong>, consolid\u00e1ndose como uno de los 23 seleccionados para esta edici\u00f3n y el \u00fanico en representar a Puerto Rico. Adem\u00e1s, Rivera Carbonell obtuvo la puntuaci\u00f3n m\u00e1s alta en el riguroso proceso de evaluaci\u00f3n del Ministerio de Cultura del Gobierno de Espa\u00f1a, convirti\u00e9ndose en una de las nueve participantes beneficiadas con una ayuda econ\u00f3mica que reconoce la solidez y proyecci\u00f3n internacional de su propuesta.<\/p>\n<p>El proyecto <em>Para\u00edso Infernal<\/em> tambi\u00e9n particip\u00f3 recientemente en el VIII Taller de Proyectos Cinematogr\u00e1ficos de Centroam\u00e9rica y el Caribe, organizado por Ibermedia en diciembre de 2024, consolidando as\u00ed su camino de desarrollo y fortalecimiento.<\/p>\n<blockquote><p><em>&#8220;Estoy m\u00e1s que feliz de poder ser parte de este curso, s\u00e9 que para noviembre tendr\u00e9 la versi\u00f3n final de Para\u00edso Infernal y comenzaremos con la b\u00fasqueda de financiaci\u00f3n. Esperamos conseguir\u00a0 que la Corporaci\u00f3n de Cine nos apoye econ\u00f3micamente para poder realizar esta pel\u00edcula. Participar en el <\/em>CDPAI,<em> es una gran vitrina para Puerto Rico y asegura que el proyecto se vea con buenos ojos en futuros festivales internacionales.&#8221;<\/em>, expres\u00f3 Maite Rivera Carbonell.<\/p><\/blockquote>\n<p>La selecci\u00f3n de Maite Rivera Carbonell y <em>Para\u00edso Infernal<\/em> representa un nuevo reconocimiento a la calidad y el potencial del cine puertorrique\u00f1o en el panorama audiovisual internacional.<\/p>\n<p>La casa productora boricua <strong>Quenepa Producciones<\/strong> ser\u00e1 la encargada de liderar el desarrollo financiero del proyecto, mientras que Tristana Robles asumir\u00e1 la responsabilidad de la producci\u00f3n ejecutiva, conformando un equipo s\u00f3lido y comprometido para llevar la pel\u00edcula a buen puerto.<\/p>\n<p>Maite Rivera Carbonell no es nueva en este prestigioso programa: en 2008 fue seleccionada para la sexta edici\u00f3n del Curso con su documental <em>Las Carpetas<\/em>, que posteriormente recibi\u00f3 importantes reconocimientos como el Segundo Premio Coral en el Festival Internacional del Nuevo Cine Latinoamericano de La Habana (2011), el Mejor Documental Canario en MiradasDoc (2012) y una Menci\u00f3n Especial del Jurado en el Festival Internacional de San Juan (2012).<\/p>\n<p>Con m\u00e1s de 25 a\u00f1os de experiencia, su amplia trayectoria en el cine est\u00e1 marcada por dos <strong>Premios Goya al Mejor Sonido<\/strong>: en 2001 por <em>The Others<\/em> de Alejandro Amen\u00e1bar y en 2009 por <em>Tres D\u00edas<\/em> de F. Javier Guti\u00e9rrez. Tambi\u00e9n ha recibido reconocimientos internacionales por su cortometraje <em>La Nota Final<\/em>, incluyendo una Menci\u00f3n Especial en el Festival de Berl\u00edn (KinderFilm Fest, 2001) y el premio al Mejor Cortometraje de Ficci\u00f3n en DiverCine, Uruguay (2001).<\/p>\n<p>El CDPAI, dirigido y coordinado por el director y productor espa\u00f1ol <strong>Gerardo Herrero<\/strong> y la directora, guionista y gestora argentina <strong>Mariana Barassi<\/strong>, es una de las residencias de gui\u00f3n m\u00e1s prestigiosas de Iberoam\u00e9rica. Desde 2003 ha reunido a m\u00e1s de 500 cineastas iberoamericanos, muchos de los cuales han llevado sus proyectos a festivales internacionales y salas comerciales. El programa ofrece asesor\u00edas de gui\u00f3n, encuentros de producci\u00f3n, talleres de pitching y masterclasses con destacados profesionales del cine iberoamericano.<\/p>\n<p>El Curso cuenta con el respaldo de <strong>Fundaci\u00f3n Carolina, EGEDA, Fundaci\u00f3n SGAE, DAMA, el Programa Ibermedia y el Ministerio de Cultura del Gobierno de Espa\u00f1a<\/strong>, adem\u00e1s de la colaboraci\u00f3n de <strong>Casa de Am\u00e9rica, Projeto Paradiso, la Red Colombiana de Escritores Audiovisuales REDES SGC y el Instituto Cervantes<\/strong>.<\/p>\n<p>La producci\u00f3n comenzar\u00e1 pr\u00f3ximamente la b\u00fasqueda inicial de financiamiento e inversionistas para el desarrollo del largometraje Para\u00edso Infernal. Aquellos interesados en ser parte del proyecto pueden comunicarse a<strong> quenepaproducciones@gmail.com<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Es seleccionado para prestigiosa residencia en Espa\u00f1a. La cineasta puertorrique\u00f1a Maite Rivera Carbonell ha sido seleccionada para participar en la vig\u00e9sima tercera edici\u00f3n del Curso de Desarrollo de Proyectos Audiovisuales Iberoamericanos (CDPAI), una reconocida residencia internacional que se celebrar\u00e1 en Madrid, Espa\u00f1a,&hellip;<\/p>\n","protected":false},"author":990002,"featured_media":6227,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","footnotes":""},"categories":[171],"tags":[],"class_list":["post-6223","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El nuevo largometraje de Maite Rivera Carbonell destaca entre m\u00e1s de 700 propuestas - CulturalPR - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/culturalpr.com\/notas\/el-nuevo-largometraje-de-maite-rivera-carbonell-destaca-entre-mas-de-700-propuestas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El nuevo largometraje de Maite Rivera Carbonell destaca entre m\u00e1s de 700 propuestas - CulturalPR - Noticias\" \/>\n<meta property=\"og:description\" content=\"\u00a0Es seleccionado para prestigiosa residencia en Espa\u00f1a. La cineasta puertorrique\u00f1a Maite Rivera Carbonell ha sido seleccionada para participar en la vig\u00e9sima tercera edici\u00f3n del Curso de Desarrollo de Proyectos Audiovisuales Iberoamericanos (CDPAI), una reconocida residencia internacional que se celebrar\u00e1 en Madrid, Espa\u00f1a,&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/culturalpr.com\/notas\/el-nuevo-largometraje-de-maite-rivera-carbonell-destaca-entre-mas-de-700-propuestas\/\" \/>\n<meta property=\"og:site_name\" content=\"CulturalPR - Noticias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/culturalpr\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-07T18:02:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/08\/Maite-Rivera-Carbonell-2-1-1024x576.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Rosalba Medina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@PasalaCultural\" \/>\n<meta name=\"twitter:site\" content=\"@PasalaCultural\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rosalba Medina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/el-nuevo-largometraje-de-maite-rivera-carbonell-destaca-entre-mas-de-700-propuestas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/el-nuevo-largometraje-de-maite-rivera-carbonell-destaca-entre-mas-de-700-propuestas\\\/\"},\"author\":{\"name\":\"Rosalba Medina\",\"@id\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/#\\\/schema\\\/person\\\/fcbcffce6aa09e518334849b38486e54\"},\"headline\":\"El nuevo largometraje de Maite Rivera Carbonell destaca entre m\u00e1s de 700 propuestas\",\"datePublished\":\"2025-08-07T18:02:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/el-nuevo-largometraje-de-maite-rivera-carbonell-destaca-entre-mas-de-700-propuestas\\\/\"},\"wordCount\":664,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/el-nuevo-largometraje-de-maite-rivera-carbonell-destaca-entre-mas-de-700-propuestas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Maite-Rivera-Carbonell-2-1.png\",\"articleSection\":[\"NOTICIAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/culturalpr.com\\\/notas\\\/el-nuevo-largometraje-de-maite-rivera-carbonell-destaca-entre-mas-de-700-propuestas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/el-nuevo-largometraje-de-maite-rivera-carbonell-destaca-entre-mas-de-700-propuestas\\\/\",\"url\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/el-nuevo-largometraje-de-maite-rivera-carbonell-destaca-entre-mas-de-700-propuestas\\\/\",\"name\":\"El nuevo largometraje de Maite Rivera Carbonell destaca entre m\u00e1s de 700 propuestas - CulturalPR - Noticias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/el-nuevo-largometraje-de-maite-rivera-carbonell-destaca-entre-mas-de-700-propuestas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/el-nuevo-largometraje-de-maite-rivera-carbonell-destaca-entre-mas-de-700-propuestas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Maite-Rivera-Carbonell-2-1.png\",\"datePublished\":\"2025-08-07T18:02:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/el-nuevo-largometraje-de-maite-rivera-carbonell-destaca-entre-mas-de-700-propuestas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/culturalpr.com\\\/notas\\\/el-nuevo-largometraje-de-maite-rivera-carbonell-destaca-entre-mas-de-700-propuestas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/el-nuevo-largometraje-de-maite-rivera-carbonell-destaca-entre-mas-de-700-propuestas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Maite-Rivera-Carbonell-2-1.png\",\"contentUrl\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Maite-Rivera-Carbonell-2-1.png\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/el-nuevo-largometraje-de-maite-rivera-carbonell-destaca-entre-mas-de-700-propuestas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El nuevo largometraje de Maite Rivera Carbonell destaca entre m\u00e1s de 700 propuestas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/#website\",\"url\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/\",\"name\":\"CulturalPR - Noticias\",\"description\":\"Puerto Rico\",\"publisher\":{\"@id\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/#organization\",\"name\":\"CulturalPR - Noticias\",\"url\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Untitled-design.png\",\"contentUrl\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Untitled-design.png\",\"width\":940,\"height\":788,\"caption\":\"CulturalPR - Noticias\"},\"image\":{\"@id\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/culturalpr\",\"https:\\\/\\\/x.com\\\/PasalaCultural\",\"https:\\\/\\\/www.instagram.com\\\/culturalpr\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/#\\\/schema\\\/person\\\/fcbcffce6aa09e518334849b38486e54\",\"name\":\"Rosalba Medina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2803a8602f74f9b5a53ce7e64cbade1dd09ac45aab49c75e6b85bdd91dc93b21?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2803a8602f74f9b5a53ce7e64cbade1dd09ac45aab49c75e6b85bdd91dc93b21?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2803a8602f74f9b5a53ce7e64cbade1dd09ac45aab49c75e6b85bdd91dc93b21?s=96&d=mm&r=g\",\"caption\":\"Rosalba Medina\"},\"url\":\"https:\\\/\\\/culturalpr.com\\\/notas\\\/author\\\/rosalba\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El nuevo largometraje de Maite Rivera Carbonell destaca entre m\u00e1s de 700 propuestas - CulturalPR - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/culturalpr.com\/notas\/el-nuevo-largometraje-de-maite-rivera-carbonell-destaca-entre-mas-de-700-propuestas\/","og_locale":"es_ES","og_type":"article","og_title":"El nuevo largometraje de Maite Rivera Carbonell destaca entre m\u00e1s de 700 propuestas - CulturalPR - Noticias","og_description":"\u00a0Es seleccionado para prestigiosa residencia en Espa\u00f1a. La cineasta puertorrique\u00f1a Maite Rivera Carbonell ha sido seleccionada para participar en la vig\u00e9sima tercera edici\u00f3n del Curso de Desarrollo de Proyectos Audiovisuales Iberoamericanos (CDPAI), una reconocida residencia internacional que se celebrar\u00e1 en Madrid, Espa\u00f1a,&hellip;","og_url":"https:\/\/culturalpr.com\/notas\/el-nuevo-largometraje-de-maite-rivera-carbonell-destaca-entre-mas-de-700-propuestas\/","og_site_name":"CulturalPR - Noticias","article_publisher":"https:\/\/www.facebook.com\/culturalpr","article_published_time":"2025-08-07T18:02:08+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/08\/Maite-Rivera-Carbonell-2-1-1024x576.png","type":"image\/png"}],"author":"Rosalba Medina","twitter_card":"summary_large_image","twitter_creator":"@PasalaCultural","twitter_site":"@PasalaCultural","twitter_misc":{"Escrito por":"Rosalba Medina","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/culturalpr.com\/notas\/el-nuevo-largometraje-de-maite-rivera-carbonell-destaca-entre-mas-de-700-propuestas\/#article","isPartOf":{"@id":"https:\/\/culturalpr.com\/notas\/el-nuevo-largometraje-de-maite-rivera-carbonell-destaca-entre-mas-de-700-propuestas\/"},"author":{"name":"Rosalba Medina","@id":"https:\/\/culturalpr.com\/notas\/#\/schema\/person\/fcbcffce6aa09e518334849b38486e54"},"headline":"El nuevo largometraje de Maite Rivera Carbonell destaca entre m\u00e1s de 700 propuestas","datePublished":"2025-08-07T18:02:08+00:00","mainEntityOfPage":{"@id":"https:\/\/culturalpr.com\/notas\/el-nuevo-largometraje-de-maite-rivera-carbonell-destaca-entre-mas-de-700-propuestas\/"},"wordCount":664,"commentCount":0,"publisher":{"@id":"https:\/\/culturalpr.com\/notas\/#organization"},"image":{"@id":"https:\/\/culturalpr.com\/notas\/el-nuevo-largometraje-de-maite-rivera-carbonell-destaca-entre-mas-de-700-propuestas\/#primaryimage"},"thumbnailUrl":"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/08\/Maite-Rivera-Carbonell-2-1.png","articleSection":["NOTICIAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/culturalpr.com\/notas\/el-nuevo-largometraje-de-maite-rivera-carbonell-destaca-entre-mas-de-700-propuestas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/culturalpr.com\/notas\/el-nuevo-largometraje-de-maite-rivera-carbonell-destaca-entre-mas-de-700-propuestas\/","url":"https:\/\/culturalpr.com\/notas\/el-nuevo-largometraje-de-maite-rivera-carbonell-destaca-entre-mas-de-700-propuestas\/","name":"El nuevo largometraje de Maite Rivera Carbonell destaca entre m\u00e1s de 700 propuestas - CulturalPR - Noticias","isPartOf":{"@id":"https:\/\/culturalpr.com\/notas\/#website"},"primaryImageOfPage":{"@id":"https:\/\/culturalpr.com\/notas\/el-nuevo-largometraje-de-maite-rivera-carbonell-destaca-entre-mas-de-700-propuestas\/#primaryimage"},"image":{"@id":"https:\/\/culturalpr.com\/notas\/el-nuevo-largometraje-de-maite-rivera-carbonell-destaca-entre-mas-de-700-propuestas\/#primaryimage"},"thumbnailUrl":"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/08\/Maite-Rivera-Carbonell-2-1.png","datePublished":"2025-08-07T18:02:08+00:00","breadcrumb":{"@id":"https:\/\/culturalpr.com\/notas\/el-nuevo-largometraje-de-maite-rivera-carbonell-destaca-entre-mas-de-700-propuestas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/culturalpr.com\/notas\/el-nuevo-largometraje-de-maite-rivera-carbonell-destaca-entre-mas-de-700-propuestas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/culturalpr.com\/notas\/el-nuevo-largometraje-de-maite-rivera-carbonell-destaca-entre-mas-de-700-propuestas\/#primaryimage","url":"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/08\/Maite-Rivera-Carbonell-2-1.png","contentUrl":"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2025\/08\/Maite-Rivera-Carbonell-2-1.png","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/culturalpr.com\/notas\/el-nuevo-largometraje-de-maite-rivera-carbonell-destaca-entre-mas-de-700-propuestas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/culturalpr.com\/notas\/"},{"@type":"ListItem","position":2,"name":"El nuevo largometraje de Maite Rivera Carbonell destaca entre m\u00e1s de 700 propuestas"}]},{"@type":"WebSite","@id":"https:\/\/culturalpr.com\/notas\/#website","url":"https:\/\/culturalpr.com\/notas\/","name":"CulturalPR - Noticias","description":"Puerto Rico","publisher":{"@id":"https:\/\/culturalpr.com\/notas\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/culturalpr.com\/notas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/culturalpr.com\/notas\/#organization","name":"CulturalPR - Noticias","url":"https:\/\/culturalpr.com\/notas\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/culturalpr.com\/notas\/#\/schema\/logo\/image\/","url":"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2024\/03\/Untitled-design.png","contentUrl":"https:\/\/culturalpr.com\/notas\/wp-content\/uploads\/2024\/03\/Untitled-design.png","width":940,"height":788,"caption":"CulturalPR - Noticias"},"image":{"@id":"https:\/\/culturalpr.com\/notas\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/culturalpr","https:\/\/x.com\/PasalaCultural","https:\/\/www.instagram.com\/culturalpr\/"]},{"@type":"Person","@id":"https:\/\/culturalpr.com\/notas\/#\/schema\/person\/fcbcffce6aa09e518334849b38486e54","name":"Rosalba Medina","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2803a8602f74f9b5a53ce7e64cbade1dd09ac45aab49c75e6b85bdd91dc93b21?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2803a8602f74f9b5a53ce7e64cbade1dd09ac45aab49c75e6b85bdd91dc93b21?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2803a8602f74f9b5a53ce7e64cbade1dd09ac45aab49c75e6b85bdd91dc93b21?s=96&d=mm&r=g","caption":"Rosalba Medina"},"url":"https:\/\/culturalpr.com\/notas\/author\/rosalba\/"}]}},"views":244,"_links":{"self":[{"href":"https:\/\/culturalpr.com\/notas\/wp-json\/wp\/v2\/posts\/6223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/culturalpr.com\/notas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/culturalpr.com\/notas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/culturalpr.com\/notas\/wp-json\/wp\/v2\/users\/990002"}],"replies":[{"embeddable":true,"href":"https:\/\/culturalpr.com\/notas\/wp-json\/wp\/v2\/comments?post=6223"}],"version-history":[{"count":2,"href":"https:\/\/culturalpr.com\/notas\/wp-json\/wp\/v2\/posts\/6223\/revisions"}],"predecessor-version":[{"id":6226,"href":"https:\/\/culturalpr.com\/notas\/wp-json\/wp\/v2\/posts\/6223\/revisions\/6226"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/culturalpr.com\/notas\/wp-json\/wp\/v2\/media\/6227"}],"wp:attachment":[{"href":"https:\/\/culturalpr.com\/notas\/wp-json\/wp\/v2\/media?parent=6223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/culturalpr.com\/notas\/wp-json\/wp\/v2\/categories?post=6223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/culturalpr.com\/notas\/wp-json\/wp\/v2\/tags?post=6223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}